{"id":700131180,"date":"2025-08-22T14:32:12","date_gmt":"2025-08-22T12:32:12","guid":{"rendered":"https:\/\/soxs.co\/de\/?post_type=product&#038;p=700131180"},"modified":"2026-05-09T08:01:32","modified_gmt":"2026-05-09T06:01:32","slug":"originals-mittelhoch-dunkelgraue-wolle-label-cool-cat","status":"publish","type":"product","link":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/","title":{"rendered":"Originals  &#8211; Dunkelgraue Wolle &#8211; Label Cool Cat"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Mit den SOXS Originals mit Cool Cat-Label haben Sie nie wieder kalte F\u00fc\u00dfe. Diese Socken bestehen aus weicher Merinowolle und Polyamid. Das Ergebnis: warme, atmungsaktive Socken, die nicht kratzen und lange sch\u00f6n bleiben. Dank des elastischen B\u00fcndchens sind sie bequem, ohne zu dr\u00fccken, ideal f\u00fcr den t\u00e4glichen Gebrauch, zu Hause oder unterwegs.<\/p>\n","protected":false},"featured_media":700131871,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_improvement_type_select":"improve_an_existing","_thumb_yes_seoaic":false,"_frame_yes_seoaic":false,"seoaic_generate_description":"","seoaic_improve_instructions_prompt":"","seoaic_rollback_content_improvement":"","seoaic_idea_thumbnail_generator":"","thumbnail_generated":false,"thumbnail_generate_prompt":"","seoaic_article_description":""},"product_brand":[1593],"product_cat":[1652,1609,1627,1642,1391],"product_tag":[1587,1588,1589],"class_list":{"0":"post-700131180","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-soxs-co","7":"product_cat-animals","8":"product_cat-nieuwe-collectie-2025","9":"product_cat-originals","10":"product_cat-speciallabel","11":"product_cat-tiere","12":"product_tag-merinowollsocken","13":"product_tag-warme-socken","14":"product_tag-warme-wollsocken","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Originals - Dunkelgraue Wolle - Label Cool Cat - SOXS.co DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Originals - Dunkelgraue Wolle - Label Cool Cat - SOXS.co DE\" \/>\n<meta property=\"og:description\" content=\"Mit den SOXS Originals mit Cool Cat-Label haben Sie nie wieder kalte F\u00fc\u00dfe. Diese Socken bestehen aus weicher Merinowolle und Polyamid. Das Ergebnis: warme, atmungsaktive Socken, die nicht kratzen und lange sch\u00f6n bleiben. Dank des elastischen B\u00fcndchens sind sie bequem, ohne zu dr\u00fccken, ideal f\u00fcr den t\u00e4glichen Gebrauch, zu Hause oder unterwegs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/\" \/>\n<meta property=\"og:site_name\" content=\"SOXS.co DE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/soxs.co\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T06:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soxs.co\/app\/uploads\/sites\/2\/2025\/07\/SOX3837-38_1000x1000px-810x810.png\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@soxs_co\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/\",\"url\":\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/\",\"name\":\"Originals - Dunkelgraue Wolle - Label Cool Cat - SOXS.co DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soxs.co\\\/app\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/SOX3837-38_1000x1000px.png\",\"datePublished\":\"2025-08-22T12:32:12+00:00\",\"dateModified\":\"2026-05-09T06:01:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soxs.co\\\/app\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/SOX3837-38_1000x1000px.png\",\"contentUrl\":\"https:\\\/\\\/soxs.co\\\/app\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/SOX3837-38_1000x1000px.png\",\"width\":2362,\"height\":2362},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/soxs.co\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/soxs.co\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Originals &#8211; Dunkelgraue Wolle &#8211; Label Cool Cat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soxs.co\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/soxs.co\\\/de\\\/\",\"name\":\"SOXS.co DE\",\"description\":\"Trendige und wunderbar warme Socken f\u00fcr alle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soxs.co\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Originals - Dunkelgraue Wolle - Label Cool Cat - SOXS.co DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/","og_locale":"de_DE","og_type":"article","og_title":"Originals - Dunkelgraue Wolle - Label Cool Cat - SOXS.co DE","og_description":"Mit den SOXS Originals mit Cool Cat-Label haben Sie nie wieder kalte F\u00fc\u00dfe. Diese Socken bestehen aus weicher Merinowolle und Polyamid. Das Ergebnis: warme, atmungsaktive Socken, die nicht kratzen und lange sch\u00f6n bleiben. Dank des elastischen B\u00fcndchens sind sie bequem, ohne zu dr\u00fccken, ideal f\u00fcr den t\u00e4glichen Gebrauch, zu Hause oder unterwegs.","og_url":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/","og_site_name":"SOXS.co DE","article_publisher":"https:\/\/www.facebook.com\/soxs.co\/","article_modified_time":"2026-05-09T06:01:32+00:00","og_image":[{"width":810,"height":810,"url":"https:\/\/soxs.co\/app\/uploads\/sites\/2\/2025\/07\/SOX3837-38_1000x1000px-810x810.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@soxs_co","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/","url":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/","name":"Originals - Dunkelgraue Wolle - Label Cool Cat - SOXS.co DE","isPartOf":{"@id":"https:\/\/soxs.co\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/#primaryimage"},"image":{"@id":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/#primaryimage"},"thumbnailUrl":"https:\/\/soxs.co\/app\/uploads\/sites\/2\/2025\/07\/SOX3837-38_1000x1000px.png","datePublished":"2025-08-22T12:32:12+00:00","dateModified":"2026-05-09T06:01:32+00:00","breadcrumb":{"@id":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/#primaryimage","url":"https:\/\/soxs.co\/app\/uploads\/sites\/2\/2025\/07\/SOX3837-38_1000x1000px.png","contentUrl":"https:\/\/soxs.co\/app\/uploads\/sites\/2\/2025\/07\/SOX3837-38_1000x1000px.png","width":2362,"height":2362},{"@type":"BreadcrumbList","@id":"https:\/\/soxs.co\/de\/originals-mittelhoch-dunkelgraue-wolle-label-cool-cat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/soxs.co\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/soxs.co\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Originals &#8211; Dunkelgraue Wolle &#8211; Label Cool Cat"}]},{"@type":"WebSite","@id":"https:\/\/soxs.co\/de\/#website","url":"https:\/\/soxs.co\/de\/","name":"SOXS.co DE","description":"Trendige und wunderbar warme Socken f\u00fcr alle","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soxs.co\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/product\/700131180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/comments?post=700131180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/media\/700131871"}],"wp:attachment":[{"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/media?parent=700131180"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/product_brand?post=700131180"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/product_cat?post=700131180"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soxs.co\/de\/wp-json\/wp\/v2\/product_tag?post=700131180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}