{"id":700129025,"date":"2024-05-15T11:59:04","date_gmt":"2024-05-15T09:59:04","guid":{"rendered":"https:\/\/soxs.co\/ch\/?post_type=product&#038;p=700129025"},"modified":"2025-09-13T15:58:49","modified_gmt":"2025-09-13T13:58:49","slug":"soxs-pullover-candy-pink-rundhalsausschnitt-unisex","status":"publish","type":"product","link":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/","title":{"rendered":"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex"},"content":{"rendered":"<p>Bringen Sie Ihr Outfit zum Strahlen mit diesem Pullover in Candy Pink aus 100 % Baumwolle. Dieser Pullover verzaubert nicht nur mit seiner verspielten rosa Farbe, sondern bietet auch ultimativen Komfort. Ob Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt. Der Candy Pink Pullover von SOXS ist ein vielseitiges Must-Have, das m\u00fchelos Weichheit und Mode verbindet. Entscheiden Sie sich f\u00fcr diesen zeitlosen Klassiker und entdecken Sie selbst, wie sich Komfort und Stil vereinen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bringen Sie Ihr Outfit zum Strahlen mit diesem Pullover in Candy Pink aus 100 % Baumwolle. Dieser Pullover verzaubert nicht nur mit seiner verspielten rosa Farbe, sondern bietet auch ultimativen Komfort. Ob Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt. Der Candy Pink Pullover von SOXS ist ein vielseitiges Must-Have, das m\u00fchelos Weichheit und Mode verbindet. Entscheiden Sie sich f\u00fcr diesen zeitlosen Klassiker und entdecken Sie selbst, wie sich Komfort und Stil vereinen.<\/p>\n","protected":false},"featured_media":700133128,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_improvement_type_select":"improve_an_existing","_thumb_yes_seoaic":false,"_frame_yes_seoaic":false,"seoaic_generate_description":"","seoaic_improve_instructions_prompt":"","seoaic_rollback_content_improvement":"","seoaic_idea_thumbnail_generator":"","thumbnail_generated":false,"thumbnail_generate_prompt":"","seoaic_article_description":""},"product_brand":[],"product_cat":[1491,96],"product_tag":[],"class_list":{"0":"post-700129025","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-loungewear","7":"product_cat-specials","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable","16":"has-default-attributes"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOXS Pullover Candy Pink Rundhalsausschnitt Unisex - SOXS.co CH<\/title>\n<meta name=\"description\" content=\"Baumwolle Pullover Pink. b Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex - SOXS.co CH\" \/>\n<meta property=\"og:description\" content=\"Baumwolle Pullover Pink. b Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/\" \/>\n<meta property=\"og:site_name\" content=\"SOXS.co CH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/soxs.co\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-13T13:58:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soxs.co\/app\/uploads\/sites\/6\/2025\/08\/Sweater-Candy-pink.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@soxs_co\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/\",\"url\":\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/\",\"name\":\"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex - SOXS.co CH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soxs.co\\\/app\\\/uploads\\\/sites\\\/6\\\/2025\\\/08\\\/Sweater-Candy-pink.jpg\",\"datePublished\":\"2024-05-15T09:59:04+00:00\",\"dateModified\":\"2025-09-13T13:58:49+00:00\",\"description\":\"Baumwolle Pullover Pink. b Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soxs.co\\\/app\\\/uploads\\\/sites\\\/6\\\/2025\\\/08\\\/Sweater-Candy-pink.jpg\",\"contentUrl\":\"https:\\\/\\\/soxs.co\\\/app\\\/uploads\\\/sites\\\/6\\\/2025\\\/08\\\/Sweater-Candy-pink.jpg\",\"caption\":\"Sweater Candy pink\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/soxs.co\\\/ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/soxs.co\\\/ch\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soxs.co\\\/ch\\\/#website\",\"url\":\"https:\\\/\\\/soxs.co\\\/ch\\\/\",\"name\":\"SOXS.co CH\",\"description\":\"Trendige und wunderbar warme Socken f\u00fcr alle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soxs.co\\\/ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex - SOXS.co CH","description":"Baumwolle Pullover Pink. b Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex - SOXS.co CH","og_description":"Baumwolle Pullover Pink. b Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt.","og_url":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/","og_site_name":"SOXS.co CH","article_publisher":"https:\/\/www.facebook.com\/soxs.co\/","article_modified_time":"2025-09-13T13:58:49+00:00","og_image":[{"url":"https:\/\/soxs.co\/app\/uploads\/sites\/6\/2025\/08\/Sweater-Candy-pink.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@soxs_co","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/","url":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/","name":"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex - SOXS.co CH","isPartOf":{"@id":"https:\/\/soxs.co\/ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/#primaryimage"},"image":{"@id":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/#primaryimage"},"thumbnailUrl":"https:\/\/soxs.co\/app\/uploads\/sites\/6\/2025\/08\/Sweater-Candy-pink.jpg","datePublished":"2024-05-15T09:59:04+00:00","dateModified":"2025-09-13T13:58:49+00:00","description":"Baumwolle Pullover Pink. b Sie sich zu Hause entspannen oder bei der Arbeit oder beim Ausgehen stilvoll aussehen wollen, dieser Pullover ist perfekt.","breadcrumb":{"@id":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/#primaryimage","url":"https:\/\/soxs.co\/app\/uploads\/sites\/6\/2025\/08\/Sweater-Candy-pink.jpg","contentUrl":"https:\/\/soxs.co\/app\/uploads\/sites\/6\/2025\/08\/Sweater-Candy-pink.jpg","caption":"Sweater Candy pink"},{"@type":"BreadcrumbList","@id":"https:\/\/soxs.co\/ch\/soxs-pullover-candy-pink-rundhalsausschnitt-unisex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/soxs.co\/ch\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/soxs.co\/ch\/shop\/"},{"@type":"ListItem","position":3,"name":"SOXS Pullover Candy Pink Rundhalsausschnitt Unisex"}]},{"@type":"WebSite","@id":"https:\/\/soxs.co\/ch\/#website","url":"https:\/\/soxs.co\/ch\/","name":"SOXS.co CH","description":"Trendige und wunderbar warme Socken f\u00fcr alle","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soxs.co\/ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/product\/700129025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/comments?post=700129025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/media\/700133128"}],"wp:attachment":[{"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/media?parent=700129025"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/product_brand?post=700129025"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/product_cat?post=700129025"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/soxs.co\/ch\/wp-json\/wp\/v2\/product_tag?post=700129025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}